{"id":14170,"date":"2021-06-29T23:44:15","date_gmt":"2021-06-29T20:44:15","guid":{"rendered":"https:\/\/scripts.farmradio.fm\/fr\/?post_type=radio-resource-packs&#038;p=14170"},"modified":"2023-10-12T20:47:08","modified_gmt":"2023-10-12T17:47:08","slug":"femmes-enceintes-et-covid-19","status":"publish","type":"radio-script","link":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/ressources-sur-covid-19\/femmes-enceintes-et-covid-19\/","title":{"rendered":"Femmes enceintes et COVID-19"},"content":{"rendered":"<p>La pand\u00e9mie de COVID-19 est une crise sanitaire majeure provoqu\u00e9e par une maladie infectieuse apparue en fin 2019 en Chine. En janvier 2020, la maladie a commenc\u00e9 \u00e0 se propager en Europe et en Am\u00e9rique et finit par atteindre l\u2019Afrique, puis au Burkina Faso. C\u2019est ainsi que le 3 mars 2020, les autorit\u00e9s burkinab\u00e9s ont annonc\u00e9 l&rsquo;\u00e9laboration d&rsquo;un plan budg\u00e9tis\u00e9 \u00e0 co\u00fbt de milliards. Le plan couvre plusieurs aspects de la lutte contre la COVID-19, tels que les interventions rapides, la surveillance \u00e9pid\u00e9miologique, les diagnostics et la communication. Le 9 mars 2020, le Burkina Faso a enregistr\u00e9 ses premiers cas de COVID-19. Cette annonce installa la panique au sein de la population et plusieurs mesures ont \u00e9t\u00e9 prises pour contr\u00f4ler la maladie. Une s\u00e9rie de mesures s&rsquo;ensuivent<\/p>\n<ul>\n<li>Interdiction de tous les \u00e9v\u00e9nements d&rsquo;envergure sur le territoire jusqu&rsquo;au 30 avril 2020 ;<\/li>\n<li>Fermeture de tous les lieux de culte, tels que les \u00e9glises et les mosqu\u00e9es ;<\/li>\n<li>Fermeture des \u00e9tablissements d\u2019enseignement \u00e0 partir du 16 mars 2020 ;<\/li>\n<li>Toutes les villes ayant enregistr\u00e9 au moins un cas de COVID-19 ont \u00e9t\u00e9 plac\u00e9es en confinement \u00e0 partir du 26 mars 2020 ;<\/li>\n<li>Port du masque obligatoire sur toute l&rsquo;\u00e9tendue du territoire \u00e0 compter du 27 avril 2020.<\/li>\n<\/ul>\n<p>Malgr\u00e9 ces mesures, la COVID-19 a continu\u00e9 \u00e0 se propager dans le pays, comme l\u2019indiquent l\u2019augmentation du nombre total de cas qui est pass\u00e9 de 962 en juin 2020 \u00e0 4 449 le 17 octobre, y compris 73 d\u00e9c\u00e8s depuis le d\u00e9but de la pand\u00e9mie.<\/p>\n<p>Ces statistiques soulignent la n\u00e9cessit\u00e9 de respecter les mesures barri\u00e8res. Les fr\u00e9quentations des centres de sant\u00e9 exigent d\u00e9sormais plus de pr\u00e9cautions pour tous en g\u00e9n\u00e9ral, y compris les femmes enceintes et allaitantes.<\/p>\n<p><b>L&rsquo;\u00e9tat des lieux de la COVID-19 actuellement au Burkina Faso<\/b><\/p>\n<p>\u00c0 la date du 9 juin 2021, le Burkina Faso enregistre 13 454 cas confirm\u00e9s. Ces cas se r\u00e9partissent comme suit \u00e0 cette date 13268 gu\u00e9risons, 167 d\u00e9c\u00e8s, 19 cas actifs. De fa\u00e7on globale, depuis le d\u00e9but du mois de d\u00e9cembre, on remarque une augmentation du nombre de cas par jour comparativement \u00e0 la p\u00e9riode ant\u00e9rieure au d\u00e9but du mois de novembre. La campagne pour les \u00e9lections pr\u00e9sidentielle et l\u00e9gislatives avec le rassemblement de masse pourrait \u00eatre \u00e0 l\u2019origine de cette recrudescence des cas qu&rsquo;on note depuis le d\u00e9but du mois de d\u00e9cembre.<\/p>\n<p>Quelques id\u00e9es fausses :<br \/>\n&lt;ul<\/p>\n<ul>\n<li>Le coronavirus se transmet de la m\u00e8re le f\u0153tus,<\/li>\n<li>L\u2019allaitement transmet la COVID-19 de la m\u00e8re au b\u00e9b\u00e9.<\/li>\n<\/ul>\n<p><b>Comment se fait la prise en charge des femmes enceintes et de femmes allaitantes \u00e0 cette p\u00e9riode de COVID-19?<\/b><br \/>\nLa femme enceinte ou allaitante constitue des personnes sp\u00e9cifiques du fait des diff\u00e9rents changements physiologiques notamment au syst\u00e8me immunitaire. Ces changements sont induits par la grossesse et l\u2019allaitement qui pourrait les exposer potentiellement des cas graves d&rsquo;infection donc des voies respiratoires.<\/p>\n<p>Cependant, jusqu\u2019\u00e0 maintenant, les \u00e9vidences disponibles ne montrent pas un risque plus \u00e9lev\u00e9 chez les femmes enceintes \u00e0 l&rsquo;infection \u00e0 la COVID-19 par rapport \u00e0 la population g\u00e9n\u00e9rale. Mais, selon l\u2019OMS, \u00ab les femmes enceintes ou les femmes dont la grossesse a pris fin r\u00e9cemment, celles qui sont plus \u00e2g\u00e9es, en surpoids, ou qui souffrent de maladies pr\u00e9existantes telles que l\u2019hypertension ou le diab\u00e8te semblent pr\u00e9senter un risque accru de d\u00e9velopper une forme grave de la COVID-19. \u00bb Il semble aussi que les femmes appartiennent \u00e0 ces groupes \u00ab n\u00e9cessitent plus souvent une prise en charge par les unit\u00e9s de soins intensifs que les femmes en \u00e2ge de procr\u00e9er, mais pas enceintes. \u00bb (2)<\/p>\n<p>Il existe tr\u00e8s peu de donn\u00e9es \u00e9galement sur un \u00e9ventuel impact p\u00e9rinatal * apr\u00e8s une infection par la COVID-19 pendant la grossesse ou dans le post-partum. Il n&rsquo;y a aucune preuve de transmission verticale de la m\u00e8re au f\u0153tus pendant la grossesse ou de transmission du virus COVID-19 par le lait maternel ou l&rsquo;allaitement. (2)<\/p>\n<p>Pour la prise en charge des cas au Burkina Faso, il y a deux documents essentiels : le plan de pr\u00e9paration de riposte et le guide de prise en charge et de pr\u00e9vention de la COVID-19. Ce sont ces deux documents qui encadrent la prise en charge et la gestion de la pand\u00e9mie. Puisqu&rsquo;il n&rsquo;y a aucune preuve d&rsquo;une diff\u00e9rence d&rsquo;infection entre les femmes enceintes ou allaitantes et la population g\u00e9n\u00e9rale, la prise en charge reste conform\u00e9ment donc au directive habituelle tout en suivant les mesures adapt\u00e9es pour r\u00e9duire la transmission de COVID-19.<\/p>\n<p>M\u00eame en cas de COVID-19 confirm\u00e9, il n&rsquo;y a pas de prescription particuli\u00e8re pour un accouchement comme un changement de voix d&rsquo;accouchement ou un passage d&rsquo;un accouchement vaginal \u00e0 une c\u00e9sarienne. Le plus important c&rsquo;est le respect des mesures de pr\u00e9vention au cours du travail pour les professionnels de la sant\u00e9 et les patients. Pour ce qui est de la prise en charge du nouveau-n\u00e9, il y a deux situations \u00e0 savoir. Si l&rsquo;accouchement a eu lieu dans une structure o\u00f9 une prise en charge sp\u00e9cialis\u00e9e est possible, le nouveau-n\u00e9 pourrait donc \u00eatre s\u00e9par\u00e9 de la maman jusqu&rsquo;\u00e0 gu\u00e9rison. La deuxi\u00e8me situation en l\u2019absence de prise en charge sp\u00e9cialis\u00e9e, le nouveau-n\u00e9 reste avec la maman qui doit cependant scrupuleusement respecter les mesures de pr\u00e9vention habituelles y compris le port de masque, la distanciation physique, le lavage r\u00e9gulier des mains et l&rsquo;utilisation de savon ou de solution hydro alcoolique.<\/p>\n<p>Dans tous les cas, apr\u00e8s l\u2019accouchement, le contact peau \u00e0 peau entre la m\u00e8re et l\u2019enfant est important. Ce contact permet une r\u00e9gulation de la temp\u00e9rature du nouveau-n\u00e9. Il est aussi associ\u00e9 \u00e0 un taux de survie accru parmi les nouveau-n\u00e9s, et favorise une mise en route de l\u2019allaitement, ce qui a aussi pour effet de r\u00e9duire la mortalit\u00e9. M\u00eame pour celles atteintes d\u2019une COVID-19 confirm\u00e9e ou pr\u00e9sum\u00e9e, l\u2019OMS recommande aux m\u00e8res d&rsquo;\u00e9tablir un contact imm\u00e9diat peau \u00e0 peau avec leur enfant tout en observant les mesures barri\u00e8res COVID-19, si possible. (2)<\/p>\n<p><b>Quels sont les risques encourus par les femmes enceintes et allaitantes? <\/b><\/p>\n<p>L&rsquo;infection au COVID-19 chez les femmes enceintes n&rsquo;est pas plus \u00e9lev\u00e9e que chez les femmes adultes non enceintes. Cependant, accoucher avec COVID-19 peut augmenter la probabilit\u00e9 de complications, y compris une naissance pr\u00e9matur\u00e9e, semblable \u00e0 toute maladie respiratoire. (3)<\/p>\n<p>Outrement, les mesures d\u2019isolement et de quarantaine \u00ab s\u2019ajouter aux difficult\u00e9s inh\u00e9rentes \u00e0 la grossesse \u2026 [et] rendent les femmes enceintes susceptibles de souffrir de troubles post-traumatiques. \u00bb (3)<\/p>\n<p><b>Comment prot\u00e9ger les femmes enceintes et allaitantes contre la pand\u00e9mie? <\/b><\/p>\n<p>Il n&rsquo;y a pas de mesure sp\u00e9cifique pour ces cibles.<\/p>\n<ul>\n<li>Les mesures barri\u00e8res doivent \u00eatre scrupuleusement respect\u00e9es comme en population g\u00e9n\u00e9rale et sans doute \u00eatre beaucoup plus vigilantes pour ces cibles dans le respect des mesures barri\u00e8res, comme le port du masque, la distanciation physique, le lavage r\u00e9gulier des mains, l&rsquo;utilisation de savon ou de solution hydro alcoolique lors des consultations.<\/li>\n<li>Signalez rapidement tout sympt\u00f4me tel que fi\u00e8vre, toux et difficult\u00e9s respiratoires. Si vous avez ces sympt\u00f4mes, rendez-vous dans un centre de sant\u00e9 le plus rapidement possible.<\/li>\n<li>Ne sort pas sauf si cela est vraiment n\u00e9cessaire, comme aller \u00e0 des cours, \u00e0 des rendez-vous m\u00e9dicaux ou seulement aller travailler.<\/li>\n<li>\u00c9vitez les rassemblements, \u00e9vitez de toucher les yeux, le nez, la bouche, ainsi que de respecter les r\u00e8gles d&rsquo;hygi\u00e8ne et respiratoires.<\/li>\n<li>\u00c9vitez tout contact avec toute personne connue pour avoir COVID-19 ou qui pr\u00e9sente des sympt\u00f4mes de l&rsquo;infection.<\/li>\n<li>\u00c9vitez autant que possible d&rsquo;utiliser les transports en commun.<\/li>\n<\/ul>\n<p><b>Les sages-femmes sur le terrain de la r\u00e9alit\u00e9 <\/b><\/p>\n<p>Pour les sages-femmes en g\u00e9n\u00e9ral, beaucoup de choses ont d\u00fb changer depuis l\u2019apparition de la pand\u00e9mie et cela n\u2019a pas \u00e9t\u00e9 facile.<\/p>\n<p>Au d\u00e9but avec les mesures barri\u00e8res de distanciation ce n&rsquo;\u00e9tait pas simple parce que les locaux ne sont pas adapt\u00e9s pour le respect de ces mesures barri\u00e8res. Avant, c&rsquo;est tous les jours que les femmes venaient pour les pes\u00e9es, mais, avec les sensibilisations, il y\u2019a eu une r\u00e9organisation d\u2019o\u00f9 une r\u00e9partition des femmes tout au long de la semaine. \u00c0 chaque fois il fallait dire aux femmes de porter des cache-nez.<\/p>\n<p>Avant la pand\u00e9mie, les agents de sant\u00e9 accueillaient les patients sans cache-nez. Mais maintenant, ils observent toutes les mesures barri\u00e8res et ils exigent le port des masques aux patients. Toutefois, ils parviennent \u00e0 faire comprendre aux femmes enceintes et allaitantes qui viennent en consultation la n\u00e9cessit\u00e9 de se laver les mains avant de rentrer et tout en donnant l\u2019exemple eux m\u00eame. Au niveau de la distanciation des patients, les sages-femmes avouent avoir souvent du mal \u00e0 la faire respecter, faute de places assises, ils sont oblig\u00e9s de s&rsquo;asseoir ensemble.<\/p>\n<p>Certaines sages-femmes pensent que le risque pour les femmes enceintes pendant COVID-19 est que la grossesse rend les femmes fragiles. Dans les cas o\u00f9 les femmes enceintes contractent le COVID-19, cela pourrait cr\u00e9er des complications pour la m\u00e8re ainsi que l\u2019enfant. Il n&rsquo;existe pas encore de connaissances d\u00e9finitives sur le sujet, mais une premi\u00e8re \u00e9tude sugg\u00e8re que les femmes enceintes porteuses du COVID-19 pourraient avoir une probabilit\u00e9 accrue de mortalit\u00e9 maternelle ou de complications apr\u00e8s la naissance par rapport aux femmes enceintes non porteuses du COVID-19. (4)<\/p>\n<p>Une femme qui allaite qui contracte la maladie peut infecter son enfant, tout comme un adulte peut en infecter un autre. Cependant, l&rsquo;OMS note que les femmes peuvent continuer \u00e0 allaiter leurs nourrissons si elles le souhaitent. L&rsquo;allaitement am\u00e9liore les taux de survie des nouveau-n\u00e9s et des nourrissons et a des effets b\u00e9n\u00e9fiques sur la sant\u00e9 et le d\u00e9veloppement tout au long de la vie. La recherche montre \u00e9galement que l&rsquo;allaitement est b\u00e9n\u00e9fique pour la sant\u00e9 de la m\u00e8re. L&rsquo;OMS note que pour les m\u00e8res avec COVID-19 confirm\u00e9 ou suspect\u00e9 qui choisissent d&rsquo;allaiter, il est important de respecter strictement toutes les mesures barri\u00e8res, comme mentionn\u00e9. (2)<\/p>\n<p>COVID-19 n&rsquo;a pas consid\u00e9rablement r\u00e9duit les taux de fr\u00e9quentation des centres de sant\u00e9 en Burkina Faso, bien qu&rsquo;au d\u00e9but, il y ait eu de la peur parmi le personnel ainsi que les patients. Lorsque certains patients sont arriv\u00e9s et ont \u00e9t\u00e9 touch\u00e9s par les agents de sant\u00e9, ils craignaient d&rsquo;\u00eatre infect\u00e9s car les agents de sant\u00e9 sont sur le terrain et expos\u00e9s \u00e0 des personnes infect\u00e9es par le COVID-19. Au d\u00e9but de la pand\u00e9mie, il y avait des preuves anecdotiques de femmes refusant de se rendre dans les \u00e9tablissements de sant\u00e9. Ceux qui sont venus avaient peur de rencontrer une personne infect\u00e9e \u00e0 l&rsquo;h\u00f4pital, ce qui a r\u00e9duit leur fr\u00e9quentation.<\/p>\n<p>Un rapport r\u00e9cent a examin\u00e9 plus de 500 \u00e9tablissements de sant\u00e9 dans 32 pays, dont 24 pays d&rsquo;Afrique. Le rapport a r\u00e9v\u00e9l\u00e9 qu&rsquo;en Afrique, au cours de la p\u00e9riode d&rsquo;avril \u00e0 septembre 2020, les premi\u00e8res visites de soins pr\u00e9natals ont diminu\u00e9 de 5% par rapport \u00e0 la m\u00eame p\u00e9riode de six mois en 2019, et qu&rsquo;il y a eu une diminution de 23% des visites d&rsquo;enfants de moins de cinq ans aux institutions m\u00e9dicales africaines (1).<\/p>\n<p>Il y a peu de donn\u00e9es disponibles sur l&rsquo;effet de COVID-19 sur la fourniture de services de sant\u00e9 sexuelle et reproductive. Cependant, une \u00e9tude r\u00e9cente a \u00e9valu\u00e9 l&rsquo;impact potentiel de COVID-19 sur ces services. Bien que le rapport ne se concentre pas sp\u00e9cifiquement sur l&rsquo;Afrique subsaharienne, il estime que, dans les pays \u00e0 revenu faible et interm\u00e9diaire, les cons\u00e9quences d&rsquo;une diminution de 10 % de la couverture des services de soins de grossesse et de soins n\u00e9onatals pourraient conduire \u00e0 :<\/p>\n<ul>\n<li>Cas suppl\u00e9mentaires de femmes souffrant de complications obst\u00e9triques majeures sans recevoir de soins ;<\/li>\n<li>D\u00e9c\u00e8s maternels suppl\u00e9mentaires ;<\/li>\n<li>Cas suppl\u00e9mentaires de nouveau-n\u00e9s souffrant de complications majeures sans recevoir de soins ; et,<\/li>\n<li>D\u00e9c\u00e8s suppl\u00e9mentaires de nouveau-n\u00e9s (3).<\/li>\n<\/ul>\n<p><b>Les patientes se prononcent :<\/b><\/p>\n<p>Voix des patients :<br \/>\n1. \u00ab Je peux dire que je n&rsquo;ai pas rencontr\u00e9 de difficult\u00e9s majeures. D\u00e8s les premiers cas au Burkina Faso je suis all\u00e9 au village en m\u00eame temps et j&rsquo;y ai \u00e9t\u00e9 confin\u00e9. Mais j&rsquo;ai pu respecter les dates des consultations pr\u00e9natales sans aucun probl\u00e8me et aujourd&rsquo;hui c&rsquo;est aussi mon dernier rendez-vous. \u00c0 ce niveau, j&rsquo;ai pu respecter les rendez-vous. \u00bb<\/p>\n<p>2. \u00ab Un jour, je suis venu peser mon enfant ; ils m&rsquo;ont chass\u00e9 parce que je n&rsquo;avais pas port\u00e9 de cache-nez. Ce jour-l\u00e0 \u2026 je suis parti sans peser mon enfant car ils m&rsquo;ont dit que si je ne portais pas de cache-nez pour ne pas venir. C&rsquo;\u00e9tait un autre jour que j&rsquo;avais un silencieux et je suis revenu pour pouvoir peser mon enfant. Pendant la pand\u00e9mie, les pes\u00e9es \u00e9taient limit\u00e9es, \u00e0 chaque fois qu&rsquo;ils ne prenaient qu&rsquo;une dizaine de personnes et au-del\u00e0 de ce nombre, tous les patients devaient attendre la prochaine s\u00e9ance. \u00bb<\/p>\n<p>Pour rem\u00e9dier \u00e0 ces difficult\u00e9s, des s\u00e9ances de sensibilisation sur les mesures barri\u00e8res, le lavage des mains, le port des cache-nez et la distanciation ont \u00e9t\u00e9 r\u00e9alis\u00e9es. Aussi, les dispositifs de lavage des mains ont \u00e9t\u00e9 d\u00e9pos\u00e9s aux diff\u00e9rentes entr\u00e9es des centres de sant\u00e9 et les cache-nez mis \u00e0 la disposition des femmes pour qu\u2019elles portent avant de rentrer.<\/p>\n<p><b>Definitions<\/b><br \/>\n<i>P\u00e9rinatal: <\/i>La p\u00e9riode qui pr\u00e9c\u00e8de et suit imm\u00e9diatement la naissance. La d\u00e9finition exacte de cette p\u00e9riode varie, mais elle se situe g\u00e9n\u00e9ralement entre quelques semaines avant la naissance et quelques semaines apr\u00e8s.<\/p>\n<p><i>Post-partum:<\/i> La p\u00e9riode qui suit imm\u00e9diatement la naissance.<\/p>\n<p><b>Bibliographie<\/b><\/p>\n<ol>\n<li>Le Fonds mondial de lutte contre le sida, la tuberculose et le paludisme, 2020. <i>Impact du covid-19 sur les services de lutte contre le VIH, la tuberculose et le paludisme et les syst\u00e8mes de sante : aper\u00e7u de la situation dans 502 \u00e9tablissements de sant\u00e9 en Afrique et en Asie<\/i>. <a href=\"https:\/\/www.theglobalfund.org\/media\/10777\/covid-19_2020-disruption-impact_report_fr.pdf\">https:\/\/www.theglobalfund.org\/media\/10777\/covid-19_2020-disruption-impact_report_fr.pdf <\/a><\/li>\n<li>Organisation Mondiale de la Sant\u00e9 (OMS), 2020. Questions-r\u00e9ponses sur la COVID-19 et l\u2019allaitement. <a href=\"https:\/\/www.who.int\/fr\/emergencies\/diseases\/novel-coronavirus-2019\/question-and-answers-hub\/q-a-detail\/q-a-on-covid-19-and-breastfeeding\">https:\/\/www.who.int\/fr\/emergencies\/diseases\/novel-coronavirus-2019\/question-and-answers-hub\/q-a-detail\/q-a-on-covid-19-and-breastfeeding <\/a><\/li>\n<li>Sall, M., et al., 2020. La sant\u00e9 reproductive, maternelle, n\u00e9onatale et adolescente en temps de pand\u00e9mie : Le\u00e7ons apprises et conseils pratique. Fonds des Nations Unies pour la Population Bureau R\u00e9gional pour l\u2019Afrique de l\u2019Ouest et du centre. <a href=\"https:\/\/wcaro.unfpa.org\/sites\/default\/files\/pub-pdf\/fr-rmnah-web_2.pdf\">https:\/\/wcaro.unfpa.org\/sites\/default\/files\/pub-pdf\/fr-rmnah-web_2.pdf <\/a><\/li>\n<li>Villar, J., et al., 2021. Maternal and Neonatal Morbidity and Mortality Among Pregnant Women With and Without COVID-19 Infection. The INTERCOVID Multinational Cohort Study. (Disponible qu\u2019en Anglais) JAMA Pediatrics, April 22, 2021, E1-10. <a href=\"https:\/\/jamanetwork.com\/journals\/jamapediatrics\/fullarticle\/2779182\">https:\/\/jamanetwork.com\/journals\/jamapediatrics\/fullarticle\/2779182<\/a><\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>La pand\u00e9mie de COVID-19 est une crise sanitaire majeure provoqu\u00e9e par une maladie infectieuse apparue en fin 2019 en Chine. En janvier 2020, la maladie a commenc\u00e9 \u00e0 se propager en Europe et en Am\u00e9rique et finit par atteindre l\u2019Afrique, puis au Burkina Faso. C\u2019est ainsi que le 3 mars 2020, les autorit\u00e9s burkinab\u00e9s ont&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":13363,"menu_order":0,"template":"","meta":{"footnotes":"","beyondwords_generate_audio":"","beyondwords_integration_method":"","beyondwords_project_id":"","beyondwords_content_id":"","beyondwords_preview_token":"","beyondwords_player_content":"","beyondwords_player_style":"","beyondwords_language_code":"","beyondwords_language_id":"","beyondwords_title_voice_id":"","beyondwords_body_voice_id":"","beyondwords_summary_voice_id":"","beyondwords_error_message":"","beyondwords_disabled":"","beyondwords_delete_content":"","beyondwords_podcast_id":"","beyondwords_hash":"","publish_post_to_speechkit":"","speechkit_hash":"","speechkit_generate_audio":"","speechkit_project_id":"","speechkit_podcast_id":"","speechkit_error_message":"","speechkit_disabled":"","speechkit_access_key":"","speechkit_error":"","speechkit_info":"","speechkit_response":"","speechkit_retries":"","speechkit_status":"","speechkit_updated_at":"","_speechkit_link":"","_speechkit_text":""},"script-format":[487],"package":[806],"script-category":[443],"class_list":["post-14170","radio-script","type-radio-script","status-publish","hentry","script-format-fiche-documentaire","package-806","script-category-sante"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Femmes enceintes et COVID-19 - Farm Radio Scripts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/ressources-sur-covid-19\/femmes-enceintes-et-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Femmes enceintes et COVID-19 - Farm Radio Scripts\" \/>\n<meta property=\"og:description\" content=\"La pand\u00e9mie de COVID-19 est une crise sanitaire majeure provoqu\u00e9e par une maladie infectieuse apparue en fin 2019 en Chine. En janvier 2020, la maladie a commenc\u00e9 \u00e0 se propager en Europe et en Am\u00e9rique et finit par atteindre l\u2019Afrique, puis au Burkina Faso. C\u2019est ainsi que le 3 mars 2020, les autorit\u00e9s burkinab\u00e9s ont&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/ressources-sur-covid-19\/femmes-enceintes-et-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Farm Radio Scripts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/farmradio\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-12T17:47:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@farmradio\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/ressources-sur-covid-19\\\/femmes-enceintes-et-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/ressources-sur-covid-19\\\/femmes-enceintes-et-covid-19\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#\\\/schema\\\/person\\\/18b7a85853915bd05b6fb298417f13fa\"},\"headline\":\"Femmes enceintes et COVID-19\",\"datePublished\":\"2021-06-29T20:44:15+00:00\",\"dateModified\":\"2023-10-12T17:47:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/ressources-sur-covid-19\\\/femmes-enceintes-et-covid-19\\\/\"},\"wordCount\":2555,\"publisher\":{\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#organization\"},\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/ressources-sur-covid-19\\\/femmes-enceintes-et-covid-19\\\/\",\"url\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/ressources-sur-covid-19\\\/femmes-enceintes-et-covid-19\\\/\",\"name\":\"Femmes enceintes et COVID-19 - Farm Radio Scripts\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#website\"},\"datePublished\":\"2021-06-29T20:44:15+00:00\",\"dateModified\":\"2023-10-12T17:47:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/ressources-sur-covid-19\\\/femmes-enceintes-et-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/ressources-sur-covid-19\\\/femmes-enceintes-et-covid-19\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/ressources-sur-covid-19\\\/femmes-enceintes-et-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ensemble th\u00e9matique\",\"item\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/format\\\/ensemble-thematique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ressources sur COVID-19\",\"item\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/covid-19-resources\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Femmes enceintes et COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#website\",\"url\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/\",\"name\":\"Farm Radio Scripts\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#organization\",\"name\":\"Farm Radio International\",\"url\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/scripts.farmradio.fm\\\/wp-content\\\/uploads\\\/farmRadioLogo.jpg\",\"contentUrl\":\"https:\\\/\\\/scripts.farmradio.fm\\\/wp-content\\\/uploads\\\/farmRadioLogo.jpg\",\"width\":200,\"height\":75,\"caption\":\"Farm Radio International\"},\"image\":{\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/farmradio\\\/\",\"https:\\\/\\\/x.com\\\/farmradio\",\"https:\\\/\\\/www.instagram.com\\\/farmradio\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FarmRadioInt\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#\\\/schema\\\/person\\\/18b7a85853915bd05b6fb298417f13fa\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0be6a79e523a97cd2bb91c73ff0b9805d0de7b0e09dc0a5a46a53e9c7551962?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0be6a79e523a97cd2bb91c73ff0b9805d0de7b0e09dc0a5a46a53e9c7551962?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0be6a79e523a97cd2bb91c73ff0b9805d0de7b0e09dc0a5a46a53e9c7551962?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Femmes enceintes et COVID-19 - Farm Radio Scripts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/ressources-sur-covid-19\/femmes-enceintes-et-covid-19\/","og_locale":"fr_CA","og_type":"article","og_title":"Femmes enceintes et COVID-19 - Farm Radio Scripts","og_description":"La pand\u00e9mie de COVID-19 est une crise sanitaire majeure provoqu\u00e9e par une maladie infectieuse apparue en fin 2019 en Chine. En janvier 2020, la maladie a commenc\u00e9 \u00e0 se propager en Europe et en Am\u00e9rique et finit par atteindre l\u2019Afrique, puis au Burkina Faso. C\u2019est ainsi que le 3 mars 2020, les autorit\u00e9s burkinab\u00e9s ont&hellip;","og_url":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/ressources-sur-covid-19\/femmes-enceintes-et-covid-19\/","og_site_name":"Farm Radio Scripts","article_publisher":"https:\/\/www.facebook.com\/farmradio\/","article_modified_time":"2023-10-12T17:47:08+00:00","twitter_card":"summary_large_image","twitter_site":"@farmradio","twitter_misc":{"Estimation du temps de lecture":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/ressources-sur-covid-19\/femmes-enceintes-et-covid-19\/#article","isPartOf":{"@id":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/ressources-sur-covid-19\/femmes-enceintes-et-covid-19\/"},"author":{"name":"admin","@id":"http:\/\/scripts.farmradio.fm\/fr\/#\/schema\/person\/18b7a85853915bd05b6fb298417f13fa"},"headline":"Femmes enceintes et COVID-19","datePublished":"2021-06-29T20:44:15+00:00","dateModified":"2023-10-12T17:47:08+00:00","mainEntityOfPage":{"@id":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/ressources-sur-covid-19\/femmes-enceintes-et-covid-19\/"},"wordCount":2555,"publisher":{"@id":"http:\/\/scripts.farmradio.fm\/fr\/#organization"},"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/ressources-sur-covid-19\/femmes-enceintes-et-covid-19\/","url":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/ressources-sur-covid-19\/femmes-enceintes-et-covid-19\/","name":"Femmes enceintes et COVID-19 - Farm Radio Scripts","isPartOf":{"@id":"http:\/\/scripts.farmradio.fm\/fr\/#website"},"datePublished":"2021-06-29T20:44:15+00:00","dateModified":"2023-10-12T17:47:08+00:00","breadcrumb":{"@id":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/ressources-sur-covid-19\/femmes-enceintes-et-covid-19\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/ressources-sur-covid-19\/femmes-enceintes-et-covid-19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/ressources-sur-covid-19\/femmes-enceintes-et-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/scripts.farmradio.fm\/fr\/"},{"@type":"ListItem","position":2,"name":"Ensemble th\u00e9matique","item":"https:\/\/scripts.farmradio.fm\/fr\/format\/ensemble-thematique\/"},{"@type":"ListItem","position":3,"name":"Ressources sur COVID-19","item":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/covid-19-resources\/"},{"@type":"ListItem","position":4,"name":"Femmes enceintes et COVID-19"}]},{"@type":"WebSite","@id":"http:\/\/scripts.farmradio.fm\/fr\/#website","url":"http:\/\/scripts.farmradio.fm\/fr\/","name":"Farm Radio Scripts","description":"","publisher":{"@id":"http:\/\/scripts.farmradio.fm\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/scripts.farmradio.fm\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"http:\/\/scripts.farmradio.fm\/fr\/#organization","name":"Farm Radio International","url":"http:\/\/scripts.farmradio.fm\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"http:\/\/scripts.farmradio.fm\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/scripts.farmradio.fm\/wp-content\/uploads\/farmRadioLogo.jpg","contentUrl":"https:\/\/scripts.farmradio.fm\/wp-content\/uploads\/farmRadioLogo.jpg","width":200,"height":75,"caption":"Farm Radio International"},"image":{"@id":"http:\/\/scripts.farmradio.fm\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/farmradio\/","https:\/\/x.com\/farmradio","https:\/\/www.instagram.com\/farmradio\/","https:\/\/www.youtube.com\/user\/FarmRadioInt"]},{"@type":"Person","@id":"http:\/\/scripts.farmradio.fm\/fr\/#\/schema\/person\/18b7a85853915bd05b6fb298417f13fa","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/e0be6a79e523a97cd2bb91c73ff0b9805d0de7b0e09dc0a5a46a53e9c7551962?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e0be6a79e523a97cd2bb91c73ff0b9805d0de7b0e09dc0a5a46a53e9c7551962?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e0be6a79e523a97cd2bb91c73ff0b9805d0de7b0e09dc0a5a46a53e9c7551962?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/radio-script\/14170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/radio-script"}],"about":[{"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/types\/radio-script"}],"author":[{"embeddable":true,"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/radio-script\/14170\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/radio-script\/13363"}],"wp:attachment":[{"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/media?parent=14170"}],"wp:term":[{"taxonomy":"script-format","embeddable":true,"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/script-format?post=14170"},{"taxonomy":"package","embeddable":true,"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/package?post=14170"},{"taxonomy":"script-category","embeddable":true,"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/script-category?post=14170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}