{"id":10622,"date":"1996-10-01T22:27:19","date_gmt":"1996-10-01T19:27:19","guid":{"rendered":"https:\/\/scripts.farmradio.fm\/fr\/?post_type=radio-resource-packs&#038;p=10622"},"modified":"2018-02-13T18:16:17","modified_gmt":"2018-02-13T15:16:17","slug":"combien-de-terre-perdez-vous","status":"publish","type":"radio-script","link":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/combien-de-terre-perdez-vous\/","title":{"rendered":"Combien de terre perdez vous?"},"content":{"rendered":"<p align=\"right\"><a href=\"http:\/\/scripts.farmradio.fm\/wp-content\/uploads\/042-03-Combien-de-terre-perdez-vous.docx\">Enregistrez et r\u00e9visez cette ressource sous forme de document Word.<\/a><\/p>\n<p>Un agriculteur du Guatemala propose une petite exp\u00e9rience pour calculer approximativement la quantit\u00e9 de terre perdue aux mains de l&rsquo;\u00e9rosion chaque ann\u00e9e. Comme l&rsquo;\u00e9rosion du sol varie d&rsquo;un champ \u00e0 l&rsquo;autre, cette exp\u00e9rience n&rsquo;indique pas les pertes exactes. Certains sols r\u00e9sistent \u00e0 l&rsquo;\u00e9rosion; certains cours d&rsquo;eau entra\u00eenent moins d&rsquo;\u00e9rosion; les terres tr\u00e8s en pente s&rsquo;\u00e9rodent plus que les terres planes. Cette exp\u00e9rience illustre toutefois les observations de l&rsquo;agriculteur dans une r\u00e9gion pr\u00e9cise du Guatemala.<\/p>\n<p>Dans la plupart de nos villes, des filets d&rsquo;eau coulent pr\u00e8s de nos maisons pendant la pluie. En g\u00e9n\u00e9ral, ils entra\u00eenent une partie du sol avec eux, du sol tir\u00e9 de nos terres. Le pr\u00e9sent article montre comment calculer la quantit\u00e9 de sol transport\u00e9 par un de ces cours d&rsquo;eau en une seule ann\u00e9e.<\/p>\n<p>Pour mener cette exp\u00e9rience, vous n&rsquo;aurez besoin que d&rsquo;un grand bol rempli d&rsquo;eau, d&rsquo;une poign\u00e9e de terre et d&rsquo;une balance capable de peser une once (30 grammes). M\u00e9langez une once (30 grammes) de terre dans le bol d&rsquo;eau. Le m\u00e9lange doit \u00eatre de la m\u00eame couleur que l&rsquo;eau qui s&rsquo;\u00e9coule dans les filets derri\u00e8re nos maisons chaque ann\u00e9e.<\/p>\n<p>Combien de bols d&rsquo;eau s&rsquo;\u00e9coulent \u00e0 la seconde derri\u00e8re nos maisons pendant une grosse averse? Si la colline est abrupte et que le cours d&rsquo;eau est de taille moyenne, il transporte au moins trois bols d&rsquo;eau \u00e0 la seconde. C&rsquo;est donc dire que toutes les secondes, trois onces (80 grammes) de terre se d\u00e9versent dans le cours d&rsquo;eau puisque chaque bol d&rsquo;eau transporte une once (30 grammes).<\/p>\n<p>Si trois onces (80 grammes) sont transport\u00e9es chaque seconde, combien d&rsquo;onces (de grammes) disparaissent en une minute? Comme une minute compte 60 secondes, c&rsquo;est donc trois onces (80 grammes) fois soixante secondes, soit 180 onces (5,000 grammes) de terre la minute.<\/p>\n<p>Pour simplifier les calculs, convertissons les onces en livres (grammes en kilogrammes). La livre \u00e9galant 16 onces, 180 onces divis\u00e9es par 16 donnent 11. (Divisez le nombre de grammes par 1,000 pour la conversion en kilogrammes.) C&rsquo;est donc dire que 11 livres (cinq kilogrammes) de terre sont transport\u00e9es chaque minute derri\u00e8re nos maisons.<\/p>\n<p>Supposons maintenant que pendant une grosse pluie, l&rsquo;eau ruisselle rapidement derri\u00e8re nos maisons pendant une demi\u2011heure, c&rsquo;est\u2011\u00e0\u2011dire 30 minutes. En r\u00e9alit\u00e9, le fort d\u00e9bit dure vraisemblablement plus longtemps, mais effectuons n\u00e9anmoins le calcul. C&rsquo;est donc dire que chaque jour de pluie, le cours d&rsquo;eau se d\u00e9verse pendant 30 minutes en transportant 11 livres (5 kilogrammes) de terre \u00e0 la minute pendant 30 minutes. Voil\u00e0 qui repr\u00e9sente 330 livres (150 kilogrammes) de terre transport\u00e9es par le cours d&rsquo;eau chaque jour o\u00f9 il pleut fort.<\/p>\n<p>Combien de jours de grosse pluie avons\u2011nous en une ann\u00e9e? La saison des pluies dure six mois, soit 180 jours. Supposons que sur cette p\u00e9riode, il n&rsquo;y a de grosse pluie que 50 jours, soit moins de un jour sur trois. Il pleut sans doute davantage, mais contentons\u2011nous de ces chiffres. S&rsquo;il y a 50 jours de grosse pluie par ann\u00e9e et que le cours d&rsquo;eau transporte 330 livres (150 kilogrammes) de terre par jour, c&rsquo;est 16,500 livres (7,500 kilogrammes) de terre qu&rsquo;il entra\u00eene en un an.<\/p>\n<p>C&rsquo;est donc dire que, dans le cours d&rsquo;eau d\u00e9crit plus t\u00f4t, 16,500 livres (7,500 kilogrammes) de terre sont lessiv\u00e9es chaque ann\u00e9e. L&rsquo;id\u00e9e de perdre autant de terre ne vous pla\u00eet vraisemblablement pas. Heureusement, il y a des mesures \u00e0 votre port\u00e9e dans le champ d\u00e8s maintenant pour vous aider \u00e0 conserver votre sol. Labourez toujours en suivant les courbes de niveau, ajoutez beaucoup de mati\u00e8re organique \u00e0 la terre, plantez des plantes de couverture et continuez de planter des arbres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enregistrez et r\u00e9visez cette ressource sous forme de document Word. Un agriculteur du Guatemala propose une petite exp\u00e9rience pour calculer approximativement la quantit\u00e9 de terre perdue aux mains de l&rsquo;\u00e9rosion chaque ann\u00e9e. Comme l&rsquo;\u00e9rosion du sol varie d&rsquo;un champ \u00e0 l&rsquo;autre, cette exp\u00e9rience n&rsquo;indique pas les pertes exactes. Certains sols r\u00e9sistent \u00e0 l&rsquo;\u00e9rosion; certains cours&hellip;<\/p>\n","protected":false},"author":142,"featured_media":0,"parent":0,"menu_order":3,"template":"","meta":{"footnotes":"","beyondwords_generate_audio":"","beyondwords_project_id":"","beyondwords_content_id":"","beyondwords_integration_method":"","beyondwords_language_code":"","beyondwords_language_id":"","beyondwords_body_voice_id":"","beyondwords_delete_content":"","beyondwords_source":"","beyondwords_output":"","beyondwords_script_template_id":"","beyondwords_video_template_id":"","beyondwords_video_size":"","beyondwords_embed":"","beyondwords_podcast_id":"","speechkit_generate_audio":"","speechkit_project_id":"","speechkit_podcast_id":""},"script-format":[487],"package":[714],"script-category":[443],"class_list":["post-10622","radio-script","type-radio-script","status-publish","hentry","script-format-fiche-documentaire","package-714","script-category-sante"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Combien de terre perdez vous? - Farm Radio Scripts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/combien-de-terre-perdez-vous\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Combien de terre perdez vous? - Farm Radio Scripts\" \/>\n<meta property=\"og:description\" content=\"Enregistrez et r\u00e9visez cette ressource sous forme de document Word. Un agriculteur du Guatemala propose une petite exp\u00e9rience pour calculer approximativement la quantit\u00e9 de terre perdue aux mains de l&rsquo;\u00e9rosion chaque ann\u00e9e. Comme l&rsquo;\u00e9rosion du sol varie d&rsquo;un champ \u00e0 l&rsquo;autre, cette exp\u00e9rience n&rsquo;indique pas les pertes exactes. Certains sols r\u00e9sistent \u00e0 l&rsquo;\u00e9rosion; certains cours&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/combien-de-terre-perdez-vous\/\" \/>\n<meta property=\"og:site_name\" content=\"Farm Radio Scripts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/farmradio\/\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-13T15:16:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@farmradio\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/combien-de-terre-perdez-vous\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/combien-de-terre-perdez-vous\\\/\"},\"author\":{\"name\":\"Farm Radio International\",\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#\\\/schema\\\/person\\\/abc034e69b53cb6ac441ffa927f22648\"},\"headline\":\"Combien de terre perdez vous?\",\"datePublished\":\"1996-10-01T19:27:19+00:00\",\"dateModified\":\"2018-02-13T15:16:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/combien-de-terre-perdez-vous\\\/\"},\"wordCount\":669,\"publisher\":{\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#organization\"},\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/combien-de-terre-perdez-vous\\\/\",\"url\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/combien-de-terre-perdez-vous\\\/\",\"name\":\"Combien de terre perdez vous? - Farm Radio Scripts\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#website\"},\"datePublished\":\"1996-10-01T19:27:19+00:00\",\"dateModified\":\"2018-02-13T15:16:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/combien-de-terre-perdez-vous\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/combien-de-terre-perdez-vous\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/texte-radiophonique\\\/combien-de-terre-perdez-vous\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fiche documentaire\",\"item\":\"https:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/format\\\/fiche-documentaire\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Combien de terre perdez vous?\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#website\",\"url\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/\",\"name\":\"Farm Radio Scripts\",\"description\":\"\",\"publisher\":{\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#organization\",\"name\":\"Farm Radio International\",\"url\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/scripts.farmradio.fm\\\/wp-content\\\/uploads\\\/farmRadioLogo.jpg\",\"contentUrl\":\"https:\\\/\\\/scripts.farmradio.fm\\\/wp-content\\\/uploads\\\/farmRadioLogo.jpg\",\"width\":200,\"height\":75,\"caption\":\"Farm Radio International\"},\"image\":{\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/farmradio\\\/\",\"https:\\\/\\\/x.com\\\/farmradio\",\"https:\\\/\\\/www.instagram.com\\\/farmradio\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/FarmRadioInt\"]},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/scripts.farmradio.fm\\\/fr\\\/#\\\/schema\\\/person\\\/abc034e69b53cb6ac441ffa927f22648\",\"name\":\"Farm Radio International\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/493231adf65be6b99ae1dc0dfb13ccca3d412c29f85aa9727be6190faa6293cd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/493231adf65be6b99ae1dc0dfb13ccca3d412c29f85aa9727be6190faa6293cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/493231adf65be6b99ae1dc0dfb13ccca3d412c29f85aa9727be6190faa6293cd?s=96&d=mm&r=g\",\"caption\":\"Farm Radio International\"},\"sameAs\":[\"http:\\\/\\\/frrp.wpengine.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Combien de terre perdez vous? - Farm Radio Scripts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/combien-de-terre-perdez-vous\/","og_locale":"fr_CA","og_type":"article","og_title":"Combien de terre perdez vous? - Farm Radio Scripts","og_description":"Enregistrez et r\u00e9visez cette ressource sous forme de document Word. Un agriculteur du Guatemala propose une petite exp\u00e9rience pour calculer approximativement la quantit\u00e9 de terre perdue aux mains de l&rsquo;\u00e9rosion chaque ann\u00e9e. Comme l&rsquo;\u00e9rosion du sol varie d&rsquo;un champ \u00e0 l&rsquo;autre, cette exp\u00e9rience n&rsquo;indique pas les pertes exactes. Certains sols r\u00e9sistent \u00e0 l&rsquo;\u00e9rosion; certains cours&hellip;","og_url":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/combien-de-terre-perdez-vous\/","og_site_name":"Farm Radio Scripts","article_publisher":"https:\/\/www.facebook.com\/farmradio\/","article_modified_time":"2018-02-13T15:16:17+00:00","twitter_card":"summary_large_image","twitter_site":"@farmradio","twitter_misc":{"Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/combien-de-terre-perdez-vous\/#article","isPartOf":{"@id":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/combien-de-terre-perdez-vous\/"},"author":{"name":"Farm Radio International","@id":"http:\/\/scripts.farmradio.fm\/fr\/#\/schema\/person\/abc034e69b53cb6ac441ffa927f22648"},"headline":"Combien de terre perdez vous?","datePublished":"1996-10-01T19:27:19+00:00","dateModified":"2018-02-13T15:16:17+00:00","mainEntityOfPage":{"@id":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/combien-de-terre-perdez-vous\/"},"wordCount":669,"publisher":{"@id":"http:\/\/scripts.farmradio.fm\/fr\/#organization"},"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/combien-de-terre-perdez-vous\/","url":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/combien-de-terre-perdez-vous\/","name":"Combien de terre perdez vous? - Farm Radio Scripts","isPartOf":{"@id":"http:\/\/scripts.farmradio.fm\/fr\/#website"},"datePublished":"1996-10-01T19:27:19+00:00","dateModified":"2018-02-13T15:16:17+00:00","breadcrumb":{"@id":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/combien-de-terre-perdez-vous\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/combien-de-terre-perdez-vous\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/scripts.farmradio.fm\/fr\/texte-radiophonique\/combien-de-terre-perdez-vous\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/scripts.farmradio.fm\/fr\/"},{"@type":"ListItem","position":2,"name":"Fiche documentaire","item":"https:\/\/scripts.farmradio.fm\/fr\/format\/fiche-documentaire\/"},{"@type":"ListItem","position":3,"name":"Combien de terre perdez vous?"}]},{"@type":"WebSite","@id":"http:\/\/scripts.farmradio.fm\/fr\/#website","url":"http:\/\/scripts.farmradio.fm\/fr\/","name":"Farm Radio Scripts","description":"","publisher":{"@id":"http:\/\/scripts.farmradio.fm\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/scripts.farmradio.fm\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"http:\/\/scripts.farmradio.fm\/fr\/#organization","name":"Farm Radio International","url":"http:\/\/scripts.farmradio.fm\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"http:\/\/scripts.farmradio.fm\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/scripts.farmradio.fm\/wp-content\/uploads\/farmRadioLogo.jpg","contentUrl":"https:\/\/scripts.farmradio.fm\/wp-content\/uploads\/farmRadioLogo.jpg","width":200,"height":75,"caption":"Farm Radio International"},"image":{"@id":"http:\/\/scripts.farmradio.fm\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/farmradio\/","https:\/\/x.com\/farmradio","https:\/\/www.instagram.com\/farmradio\/","https:\/\/www.youtube.com\/user\/FarmRadioInt"]},{"@type":"Person","@id":"http:\/\/scripts.farmradio.fm\/fr\/#\/schema\/person\/abc034e69b53cb6ac441ffa927f22648","name":"Farm Radio International","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/493231adf65be6b99ae1dc0dfb13ccca3d412c29f85aa9727be6190faa6293cd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/493231adf65be6b99ae1dc0dfb13ccca3d412c29f85aa9727be6190faa6293cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/493231adf65be6b99ae1dc0dfb13ccca3d412c29f85aa9727be6190faa6293cd?s=96&d=mm&r=g","caption":"Farm Radio International"},"sameAs":["http:\/\/frrp.wpengine.com"]}]}},"_links":{"self":[{"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/radio-script\/10622","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/radio-script"}],"about":[{"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/types\/radio-script"}],"author":[{"embeddable":true,"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/users\/142"}],"version-history":[{"count":0,"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/radio-script\/10622\/revisions"}],"wp:attachment":[{"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/media?parent=10622"}],"wp:term":[{"taxonomy":"script-format","embeddable":true,"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/script-format?post=10622"},{"taxonomy":"package","embeddable":true,"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/package?post=10622"},{"taxonomy":"script-category","embeddable":true,"href":"https:\/\/scripts.farmradio.fm\/fr\/wp-json\/wp\/v2\/script-category?post=10622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}